{"id":6316,"date":"2019-01-03T12:22:00","date_gmt":"2019-01-03T12:22:00","guid":{"rendered":"https:\/\/works.raqsmediacollective.net\/?p=6316"},"modified":"2024-10-09T15:15:59","modified_gmt":"2024-10-09T15:15:59","slug":"demos","status":"publish","type":"post","link":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316","title":{"rendered":"To People, Demos\u00a0&#038; Prostheses for the History of Insurgent Crowds"},"content":{"rendered":"\n<div id=\"topeople\" class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\" style=\"font-size:21px\"><em><strong>To People<br>Shown at:  Mathaf, Doha (2019)  <\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><em>11 Textile and 2 Prints on paper,<\/em><br><em>100 x 500 cm each<\/em><\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:17px\">Eleven hand-woven carpets and two paper prints are hung throughout the gallery, cascading to the ground. The forms that inhabit the woven textiles represent a mass, a collective, or a network of people as an interlaced, connected weave. The work explores the meaning of the verb \u2018to people\u2019, which can suggest populating and inhabiting a space, wilfully or enforced, but can also be read as a work that is \u2018for people\u2019, referring to one person or multiple individuals. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:17px\">The pixelated figures create a modular, blurred landscape of objects and human forms in transition. Together the carpets constitute one image of the nexus of people coming together in large urban cities. The work is produced for the exhibition in reference to the city of Doha and the wide networks of people who reside here.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped uag-masonry uagb-block-4886277c wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1438\" data-id=\"6392\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-scaled.jpg\" alt=\"\" class=\"wp-image-6392\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-scaled.jpg 2560w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-640x360.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-1280x719.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-768x432.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-1536x863.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-2048x1151.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-1024x575.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-300x169.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-890x500.jpg 890w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-24x13.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-36x20.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03041-48x27.jpg 48w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC03039-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"7737\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-scaled.jpg\" alt=\"\" class=\"wp-image-7737\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-scaled.jpg 2560w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-640x360.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-1280x720.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-768x432.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-1536x864.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-2048x1152.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-1024x576.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-300x169.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-889x500.jpg 889w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-24x14.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-36x20.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03039-edited-48x27.jpg 48w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" data-id=\"7739\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited.jpg\" alt=\"\" class=\"wp-image-7739\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-640x359.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-768x432.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-300x168.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-890x500.jpg 890w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-24x13.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-36x20.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/7fe66481-c84b-4791-8f59-809ef85e2039-edited-48x27.jpg 48w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/DSC03049-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"7735\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-scaled.jpg\" alt=\"\" class=\"wp-image-7735\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-scaled.jpg 2560w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-640x360.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-1280x720.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-768x432.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-1536x864.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-2048x1152.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-1024x576.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-300x169.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-889x500.jpg 889w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-24x14.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-36x20.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/04\/DSC03049-edited-48x27.jpg 48w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:21px\"><em><strong>Demos | Crimson, Azure (2017)<br>Shown at: Delhi Contemporary Art Week (DCAW), Nature Morte, Bikaner House, New Delhi (2021)<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><em>Multiple fused corian surfaces<\/em><br><em> 1 x 1 m<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:17px\"><em>Demos<\/em> (Crimson, Azure) are two works in a series of figural patterns from pixelated renditions of human bodies in crowds. The experience of being in the presence of many other sentiences can be one replete with contradictory sensations &#8211; a sense of fullness, of being in a flow with others, of ecstatic communion, intimacy, anonymity, claustrophobia, solidarity and heightened awareness of the proximity of other breaths, other bodies.&nbsp;<em>Demos<\/em>&nbsp;explores these sensations by deploying colour as a marker of affect.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"852\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-1280x852.jpg\" alt=\"\" class=\"wp-image-6320\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-1280x852.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-640x426.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-768x511.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-1536x1022.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-2048x1363.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-1024x681.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-300x200.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-751x500.jpg 751w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-24x16.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-36x24.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/DSC0645-48x32.jpg 48w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped uag-masonry uagb-block-b1cf26a4 wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2304\" height=\"2304\" data-id=\"6318\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure.jpg\" alt=\"\" class=\"wp-image-6318\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure.jpg 2304w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-640x640.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-1280x1280.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-768x768.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-1536x1536.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-2048x2048.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-1024x1024.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-300x300.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-500x500.jpg 500w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-24x24.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-36x36.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-48x48.jpg 48w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Azure-80x80.jpg 80w\" sizes=\"auto, (max-width: 2304px) 100vw, 2304px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1272\" height=\"1270\" data-id=\"7153\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1.jpg\" alt=\"\" class=\"wp-image-7153\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1.jpg 1272w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-640x639.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-768x767.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-1024x1022.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-300x300.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-501x500.jpg 501w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-24x24.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-36x36.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-48x48.jpg 48w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Demos-Crimson-1-edited-1-80x80.jpg 80w\" sizes=\"auto, (max-width: 1272px) 100vw, 1272px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\" style=\"font-size:21px\"><em><strong>To People, Demos\u00a0&amp; Prostheses for the History of Insurgent Crowds <br>Shown at: The Whitworth, Manchester (2017) | K21, D\u00fcsseldorf (2018)<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><em>Print &amp; Installation with Wax ex-votos and wall paper\u00a0<br>24 blocks 0f 1m x 1m each<\/em><\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">The acceleration of the assembly line is interrupted by accidents. Legs, arms, hands, eyes, and other bits of life become unpredictable crowds (found ex-votos from a Mumbai church) at the altars of progress and speed. Bodies assemble behind the limbs \u2013 pixelated human forms \u2013 to constitute a counter-collective. Who breaks whom? What is broken and what is healed?<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped uag-masonry uagb-block-ffaa2080 wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"963\" data-id=\"7148\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-1280x963.jpg\" alt=\"\" class=\"wp-image-7148\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-1280x963.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-640x481.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-768x578.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-1536x1155.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-2048x1540.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-1024x770.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-300x226.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-665x500.jpg 665w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-24x18.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-36x27.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/RaqsMedia_028362repro-min-48x36.jpg 48w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" data-id=\"7149\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-1280x960.jpg\" alt=\"\" class=\"wp-image-7149\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-1280x960.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-640x480.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-768x576.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-1536x1152.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-2048x1536.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-1024x768.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-300x225.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-667x500.jpg 667w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-24x18.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-36x27.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Photo-credits_Achim-Kukulies-min-48x36.jpg 48w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped uag-masonry uagb-block-4df70fd8 wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-id=\"7151\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-1280x1280.jpg\" alt=\"\" class=\"wp-image-7151\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-1280x1280.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-640x640.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-768x768.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-1536x1536.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-2048x2048.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-1024x1024.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-300x300.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-500x500.jpg 500w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-24x24.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-36x36.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-48x48.jpg 48w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/prostheses-min-1-80x80.jpg 80w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-id=\"7150\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-1280x1280.jpg\" alt=\"\" class=\"wp-image-7150\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-1280x1280.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-640x640.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-768x768.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-1536x1536.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-2048x2048.jpg 2048w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-1024x1024.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-300x300.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-500x500.jpg 500w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-24x24.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-36x36.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-48x48.jpg 48w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/03\/Single-Panel_Photo-credits_Achim-Kukulies-min-1-80x80.jpg 80w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:150px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>To PeopleShown at: Mathaf, Doha (2019) 11 Textile and 2 Prints on paper,100 x 500 cm each Eleven hand-woven carpets and two paper prints are hung throughout the gallery, cascading to the ground. The forms that inhabit the woven textiles represent a mass, a collective, or a network of people as an interlaced, connected weave. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[19,14],"tags":[],"class_list":["post-6316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gatherings","category-practices","has-thumbnail"],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>To People, Demos\u00a0&amp; Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"To People, Demos\u00a0&amp; Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective\" \/>\n<meta property=\"og:description\" content=\"To PeopleShown at: Mathaf, Doha (2019) 11 Textile and 2 Prints on paper,100 x 500 cm each Eleven hand-woven carpets and two paper prints are hung throughout the gallery, cascading to the ground. The forms that inhabit the woven textiles represent a mass, a collective, or a network of people as an interlaced, connected weave. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316\" \/>\n<meta property=\"og:site_name\" content=\"Works Raqs Media Collective\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-03T12:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-09T15:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raqs Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raqs Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316\"},\"author\":{\"name\":\"Raqs Web\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/person\\\/7d281c8156fb625db44d80081cb8e7a6\"},\"headline\":\"To People, Demos\u00a0&#038; Prostheses for the History of Insurgent Crowds\",\"datePublished\":\"2019-01-03T12:22:00+00:00\",\"dateModified\":\"2024-10-09T15:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316\"},\"wordCount\":351,\"publisher\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demos-Crimson-scaled.jpg\",\"articleSection\":[\"GATHERINGS\",\"PRACTICES\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316\",\"name\":\"To People, Demos\u00a0& Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demos-Crimson-scaled.jpg\",\"datePublished\":\"2019-01-03T12:22:00+00:00\",\"dateModified\":\"2024-10-09T15:15:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#primaryimage\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demos-Crimson-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Demos-Crimson-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2019\\\/01\\\/03\\\/demos\\\/6316#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"To People, Demos\u00a0&#038; Prostheses for the History of Insurgent Crowds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#website\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\",\"name\":\"Works Raqs Media Collective\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\",\"name\":\"Works Raqs Media Collective\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logoraqs-1.jpg\",\"contentUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logoraqs-1.jpg\",\"width\":110,\"height\":110,\"caption\":\"Works Raqs Media Collective\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/person\\\/7d281c8156fb625db44d80081cb8e7a6\",\"name\":\"Raqs Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"caption\":\"Raqs Web\"},\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/author\\\/raqsweb\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"To People, Demos\u00a0& Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316","og_locale":"en_US","og_type":"article","og_title":"To People, Demos\u00a0& Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective","og_description":"To PeopleShown at: Mathaf, Doha (2019) 11 Textile and 2 Prints on paper,100 x 500 cm each Eleven hand-woven carpets and two paper prints are hung throughout the gallery, cascading to the ground. The forms that inhabit the woven textiles represent a mass, a collective, or a network of people as an interlaced, connected weave. [&hellip;]","og_url":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316","og_site_name":"Works Raqs Media Collective","article_published_time":"2019-01-03T12:22:00+00:00","article_modified_time":"2024-10-09T15:15:59+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg","type":"image\/jpeg"}],"author":"Raqs Web","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Raqs Web","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#article","isPartOf":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316"},"author":{"name":"Raqs Web","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/person\/7d281c8156fb625db44d80081cb8e7a6"},"headline":"To People, Demos\u00a0&#038; Prostheses for the History of Insurgent Crowds","datePublished":"2019-01-03T12:22:00+00:00","dateModified":"2024-10-09T15:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316"},"wordCount":351,"publisher":{"@id":"https:\/\/works.raqsmediacollective.net\/#organization"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#primaryimage"},"thumbnailUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg","articleSection":["GATHERINGS","PRACTICES"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316","url":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316","name":"To People, Demos\u00a0& Prostheses for the History of Insurgent Crowds - Works Raqs Media Collective","isPartOf":{"@id":"https:\/\/works.raqsmediacollective.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#primaryimage"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#primaryimage"},"thumbnailUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg","datePublished":"2019-01-03T12:22:00+00:00","dateModified":"2024-10-09T15:15:59+00:00","breadcrumb":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#primaryimage","url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg","contentUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/01\/Demos-Crimson-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2019\/01\/03\/demos\/6316#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/works.raqsmediacollective.net\/"},{"@type":"ListItem","position":2,"name":"To People, Demos\u00a0&#038; Prostheses for the History of Insurgent Crowds"}]},{"@type":"WebSite","@id":"https:\/\/works.raqsmediacollective.net\/#website","url":"https:\/\/works.raqsmediacollective.net\/","name":"Works Raqs Media Collective","description":"","publisher":{"@id":"https:\/\/works.raqsmediacollective.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/works.raqsmediacollective.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/works.raqsmediacollective.net\/#organization","name":"Works Raqs Media Collective","url":"https:\/\/works.raqsmediacollective.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/logo\/image\/","url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2020\/03\/cropped-logoraqs-1.jpg","contentUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2020\/03\/cropped-logoraqs-1.jpg","width":110,"height":110,"caption":"Works Raqs Media Collective"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/person\/7d281c8156fb625db44d80081cb8e7a6","name":"Raqs Web","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","caption":"Raqs Web"},"url":"https:\/\/works.raqsmediacollective.net\/index.php\/author\/raqsweb"}]}},"_links":{"self":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/6316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/comments?post=6316"}],"version-history":[{"count":16,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/6316\/revisions"}],"predecessor-version":[{"id":12378,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/6316\/revisions\/12378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/media\/6317"}],"wp:attachment":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/media?parent=6316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/categories?post=6316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/tags?post=6316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}