{"id":9191,"date":"2010-08-02T10:31:00","date_gmt":"2010-08-02T10:31:00","guid":{"rendered":"https:\/\/works.raqsmediacollective.net\/?p=9191"},"modified":"2024-11-04T10:38:15","modified_gmt":"2024-11-04T10:38:15","slug":"time-is-money","status":"publish","type":"post","link":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191","title":{"rendered":"Time is Money"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1709\" height=\"781\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg\" alt=\"\" class=\"wp-image-9195\" style=\"width:514px;height:auto\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg 1709w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-640x292.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-1280x585.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-768x351.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-1536x702.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-1024x468.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-300x137.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-1000x457.jpg 1000w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-24x11.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-36x16.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4-48x22.jpg 48w\" sizes=\"auto, (max-width: 1709px) 100vw, 1709px\" \/><\/a><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-is-layout-4fc3f8e1 wp-block-group-is-layout-flex\">\n<p class=\"wp-block-paragraph\" style=\"font-size:21px\"><em><strong>Time is Money<\/strong><\/em><strong><em><br><\/em><\/strong><em><strong>Shown at: &#8216;Impossible Exchange&#8217;, Frieze Fair (2010) | Time Currency, Liverpool Biennial (2010)<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:15px\"><em>Prints<br>Series of 5, each 12 x 28 cm<\/em><\/p>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:17px\">Speculating on the concept of time, <em>Time is Money<\/em> intertwines financial and political matters related to capitalism with ontological issues related to ephemerality and permanence.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:17px\"><em>&#8220;The idea of deploying time in terms of monetary value is not a new one, and is central to the ideas of \u2018interest\u2019 in finance and the debates around usury. Perhaps the \u2018time is money\u2019 analogy stems from the notional scarcity of time in human life. Two different ideas of currency can emanate from our considerations of the value of time, depending on whether we think of time as scarce, or as abundant. The time as scarce gives rise to a currency of time that is similar to money as we know it. And this leads to the notions of \u2018saving\u2019, \u2018hoarding\u2019, \u2018wasting\u2019 and \u2018spending\u2019 time. This notion emphasizes the value of a unit of time as an abstract entity, regardless of what the time is spent on. On the other hand, if we think of time as abundant, our focus shifts from the quantity to the quality of time, and we can transact and exchange units of time that are not necessarily identical in quantity, even though we may bring them into relations of equivalence with each other.&#8221;<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped uag-masonry uagb-block-d80e1f0b wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1833\" height=\"779\" data-id=\"9192\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1.jpg\" alt=\"\" class=\"wp-image-9192\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1.jpg 1833w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-640x272.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-1280x544.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-768x326.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-1536x653.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-1024x435.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-300x127.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-1000x425.jpg 1000w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-24x10.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-36x15.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-1-48x20.jpg 48w\" sizes=\"auto, (max-width: 1833px) 100vw, 1833px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1833\" height=\"779\" data-id=\"9193\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2.jpg\" alt=\"\" class=\"wp-image-9193\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2.jpg 1833w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-640x272.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-1280x544.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-768x326.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-1536x653.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-1024x435.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-300x127.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-1000x425.jpg 1000w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-24x10.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-36x15.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-2-48x20.jpg 48w\" sizes=\"auto, (max-width: 1833px) 100vw, 1833px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1447\" height=\"782\" data-id=\"9194\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3.jpg\" alt=\"\" class=\"wp-image-9194\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3.jpg 1447w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-640x346.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-1280x692.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-768x415.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-1024x553.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-300x162.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-925x500.jpg 925w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-24x13.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-36x19.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-3-48x26.jpg 48w\" sizes=\"auto, (max-width: 1447px) 100vw, 1447px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1714\" height=\"783\" data-id=\"9196\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5.jpg\" alt=\"\" class=\"wp-image-9196\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5.jpg 1714w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-640x292.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-1280x585.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-768x351.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-1536x702.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-1024x468.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-300x137.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-1000x457.jpg 1000w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-24x11.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-36x16.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-5-48x22.jpg 48w\" sizes=\"auto, (max-width: 1714px) 100vw, 1714px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1709\" height=\"781\" data-id=\"9197\" src=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6.jpg\" alt=\"\" class=\"wp-image-9197\" srcset=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6.jpg 1709w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-640x292.jpg 640w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-1280x585.jpg 1280w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-768x351.jpg 768w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-1536x702.jpg 1536w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-1024x468.jpg 1024w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-300x137.jpg 300w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-1000x457.jpg 1000w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-24x11.jpg 24w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-36x16.jpg 36w, https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-6-48x22.jpg 48w\" sizes=\"auto, (max-width: 1709px) 100vw, 1709px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Speculating on the concept of time, Time is Money intertwines financial and political matters related to capitalism with ontological issues related to ephemerality and permanence<\/p>\n","protected":false},"author":2,"featured_media":9195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[12,14,1],"tags":[],"class_list":["post-9191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lexica","category-practices","category-works","has-thumbnail"],"gutentor_comment":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Time is Money - Works Raqs Media Collective<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Time is Money - Works Raqs Media Collective\" \/>\n<meta property=\"og:description\" content=\"Speculating on the concept of time, Time is Money intertwines financial and political matters related to capitalism with ontological issues related to ephemerality and permanence\" \/>\n<meta property=\"og:url\" content=\"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191\" \/>\n<meta property=\"og:site_name\" content=\"Works Raqs Media Collective\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-02T10:31:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T10:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1709\" \/>\n\t<meta property=\"og:image:height\" content=\"781\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raqs Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raqs Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191\"},\"author\":{\"name\":\"Raqs Web\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/person\\\/7d281c8156fb625db44d80081cb8e7a6\"},\"headline\":\"Time is Money\",\"datePublished\":\"2010-08-02T10:31:00+00:00\",\"dateModified\":\"2024-11-04T10:38:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TimeBank-4.jpg\",\"articleSection\":[\"LEXICA\",\"PRACTICES\",\"WORKS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191\",\"name\":\"Time is Money - Works Raqs Media Collective\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TimeBank-4.jpg\",\"datePublished\":\"2010-08-02T10:31:00+00:00\",\"dateModified\":\"2024-11-04T10:38:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#primaryimage\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TimeBank-4.jpg\",\"contentUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/TimeBank-4.jpg\",\"width\":1709,\"height\":781},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/2010\\\/08\\\/02\\\/time-is-money\\\/9191#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Time is Money\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#website\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\",\"name\":\"Works Raqs Media Collective\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#organization\",\"name\":\"Works Raqs Media Collective\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logoraqs-1.jpg\",\"contentUrl\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cropped-logoraqs-1.jpg\",\"width\":110,\"height\":110,\"caption\":\"Works Raqs Media Collective\"},\"image\":{\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/#\\\/schema\\\/person\\\/7d281c8156fb625db44d80081cb8e7a6\",\"name\":\"Raqs Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g\",\"caption\":\"Raqs Web\"},\"url\":\"https:\\\/\\\/works.raqsmediacollective.net\\\/index.php\\\/author\\\/raqsweb\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Time is Money - Works Raqs Media Collective","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191","og_locale":"en_US","og_type":"article","og_title":"Time is Money - Works Raqs Media Collective","og_description":"Speculating on the concept of time, Time is Money intertwines financial and political matters related to capitalism with ontological issues related to ephemerality and permanence","og_url":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191","og_site_name":"Works Raqs Media Collective","article_published_time":"2010-08-02T10:31:00+00:00","article_modified_time":"2024-11-04T10:38:15+00:00","og_image":[{"width":1709,"height":781,"url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg","type":"image\/jpeg"}],"author":"Raqs Web","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Raqs Web","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#article","isPartOf":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191"},"author":{"name":"Raqs Web","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/person\/7d281c8156fb625db44d80081cb8e7a6"},"headline":"Time is Money","datePublished":"2010-08-02T10:31:00+00:00","dateModified":"2024-11-04T10:38:15+00:00","mainEntityOfPage":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191"},"wordCount":225,"publisher":{"@id":"https:\/\/works.raqsmediacollective.net\/#organization"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#primaryimage"},"thumbnailUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg","articleSection":["LEXICA","PRACTICES","WORKS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191","url":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191","name":"Time is Money - Works Raqs Media Collective","isPartOf":{"@id":"https:\/\/works.raqsmediacollective.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#primaryimage"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#primaryimage"},"thumbnailUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg","datePublished":"2010-08-02T10:31:00+00:00","dateModified":"2024-11-04T10:38:15+00:00","breadcrumb":{"@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#primaryimage","url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg","contentUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2023\/08\/TimeBank-4.jpg","width":1709,"height":781},{"@type":"BreadcrumbList","@id":"https:\/\/works.raqsmediacollective.net\/index.php\/2010\/08\/02\/time-is-money\/9191#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/works.raqsmediacollective.net\/"},{"@type":"ListItem","position":2,"name":"Time is Money"}]},{"@type":"WebSite","@id":"https:\/\/works.raqsmediacollective.net\/#website","url":"https:\/\/works.raqsmediacollective.net\/","name":"Works Raqs Media Collective","description":"","publisher":{"@id":"https:\/\/works.raqsmediacollective.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/works.raqsmediacollective.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/works.raqsmediacollective.net\/#organization","name":"Works Raqs Media Collective","url":"https:\/\/works.raqsmediacollective.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/logo\/image\/","url":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2020\/03\/cropped-logoraqs-1.jpg","contentUrl":"https:\/\/works.raqsmediacollective.net\/wp-content\/uploads\/2020\/03\/cropped-logoraqs-1.jpg","width":110,"height":110,"caption":"Works Raqs Media Collective"},"image":{"@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/works.raqsmediacollective.net\/#\/schema\/person\/7d281c8156fb625db44d80081cb8e7a6","name":"Raqs Web","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d59527b692728b1e9398131071f42ac6704d67345e04504d80b7d239fa74a574?s=96&d=mm&r=g","caption":"Raqs Web"},"url":"https:\/\/works.raqsmediacollective.net\/index.php\/author\/raqsweb"}]}},"_links":{"self":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/9191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/comments?post=9191"}],"version-history":[{"count":5,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/9191\/revisions"}],"predecessor-version":[{"id":13179,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/posts\/9191\/revisions\/13179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/media\/9195"}],"wp:attachment":[{"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/media?parent=9191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/categories?post=9191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/works.raqsmediacollective.net\/index.php\/wp-json\/wp\/v2\/tags?post=9191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}